{"id":4237,"date":"2017-05-04T17:49:26","date_gmt":"2017-05-04T15:49:26","guid":{"rendered":"http:\/\/www.maistendencia.com\/?p=4237"},"modified":"2019-08-09T09:43:50","modified_gmt":"2019-08-09T07:43:50","slug":"micah-p-hinson-en-la-shopping-night","status":"publish","type":"post","link":"https:\/\/www.maistendencia.com\/blog\/micah-p-hinson-en-la-shopping-night\/","title":{"rendered":"Micah P. Hinson en la Shopping Night"},"content":{"rendered":"<p>La noche de la Shopping Night del Centro Comercial Aberto Ourense Centro trae tambi\u00e9n el concierto de Micah P. Hinson en colaboraci\u00f3n con la <a href=\"http:\/\/ourenseiccweek.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">ICC Week<\/a>.<\/p>\n<h2 class=\"entry-title\">Micah P. Hinson interpretar\u00e1 temas de su \u00faltimo disco.<\/h2>\n<p>Este cantaautor y guitarrista americano interpretar\u00e1 temas de su \u00faltimo disco, <em>Broken Arrows,<\/em>&nbsp;pero tambi\u00e9n har\u00e1 un recorrido por sus anteriores trabajos.<\/p>\n<p><figure id=\"attachment_4252\" aria-describedby=\"caption-attachment-4252\" style=\"width: 604px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4252\" src=\"http:\/\/www.maistendencia.com\/wp-content\/uploads\/2017\/05\/1280px-Micah_P._Hinson_422907068-1024x682.jpg\" alt=\"By Matt Biddulph from UK (micah p hinson Uploaded by Yarl) [CC BY-SA 2.0 (http:\/\/creativecommons.org\/licenses\/by-sa\/2.0)], via Wikimedia Commons\" width=\"604\" height=\"402\" srcset=\"https:\/\/www.maistendencia.com\/blog\/wp-content\/uploads\/2017\/05\/1280px-Micah_P._Hinson_422907068-1024x682.jpg 1024w, https:\/\/www.maistendencia.com\/blog\/wp-content\/uploads\/2017\/05\/1280px-Micah_P._Hinson_422907068-300x200.jpg 300w, https:\/\/www.maistendencia.com\/blog\/wp-content\/uploads\/2017\/05\/1280px-Micah_P._Hinson_422907068-400x266.jpg 400w, https:\/\/www.maistendencia.com\/blog\/wp-content\/uploads\/2017\/05\/1280px-Micah_P._Hinson_422907068-50x33.jpg 50w, https:\/\/www.maistendencia.com\/blog\/wp-content\/uploads\/2017\/05\/1280px-Micah_P._Hinson_422907068.jpg 1280w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><figcaption id=\"caption-attachment-4252\" class=\"wp-caption-text\">By Matt Biddulph from UK (micah p hinson Uploaded by Yarl) [CC BY-SA 2.0 (http:\/\/creativecommons.org\/licenses\/by-sa\/2.0)], via Wikimedia Commons<\/figcaption><\/figure>La vida de este cantante no es convencional. Nacido en el seno de una estricta familia con fuertes convicciones religiosas, pas\u00f3 su adolescencia en Texas, d\u00f3nde mantuvo una tormentosa relaci\u00f3n con una mujer mayor que \u00e9l, una modelo viuda del guitarrista de un grupo local a la que se referir\u00eda m\u00e1s adelante como \u00abviuda negra\u00bb.<\/p>\n<p>Ella le introdujo en el consumo de valium y otras substancias, llegando Micah a pasar una temporada en la c\u00e1rcel acusado de falsificaci\u00f3n de recetas. Tal como declar\u00f3 termin\u00f3 por perder su coche, su hogar, todo su dinero, sus instrumentos, su equipo de grabaci\u00f3n, y principalmente, a su familia entera.<\/p>\n<p>Al salir tuvo que comenzar de cero y vivi\u00f3 como un vagabundo, durmiendo en casa de sus amigos hasta que consigui\u00f3 un empleo en telemarketing y pudo mudarse a un motel en donde, con instrumentos prestados, compuso alrededor de 30 canciones que incluir\u00eda en sus primeros trabajos.<\/p>\n<p>Un dato curioso: los coros de sus discos siempre est\u00e1n cantados por \u00e9l mismo con diferentes entonaciones y en alguna canci\u00f3n hay hasta 15 pistas con su voz cantando al mismo tiempo<\/p>\n<p>Se le ha comparado con Jonnhy Cash, Wilco, Leonard Cohen y Nick Cave, entre otros. Hinson, por su parte, declara que&nbsp;se identifica con cantautores cercanos al pop como Elliott Smith o Iron &amp; Wine y que creci\u00f3 escuchando rock alternativo, pricipalmente grupos como My Bloody Valentines o Pixies.&nbsp;Sus letras suelen ser autobiogr\u00e1ficas&nbsp;y contienen referencias a su intensa&nbsp;vida personal.<\/p>\n<p>Ma\u00f1ana tienes una oportunidad de escucharle en directo entre compra y compra de la <strong>Shopping Night a las 21.00 en los Jardines Padre Feij\u00f3o<\/strong>, \u00a1no te lo pierdas!<\/p>\n<p>Imagen principal:&nbsp;http:\/\/ourenseiccweek.com\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noche de la Shopping Night del Centro Comercial Aberto Ourense Centro trae tambi\u00e9n el concierto de Micah P. Hinson en colaboraci\u00f3n con la ICC Week. Micah P. Hinson interpretar\u00e1 temas de su \u00faltimo disco&#8230;.<br \/><a href=\"https:\/\/www.maistendencia.com\/blog\/micah-p-hinson-en-la-shopping-night\/\"> Continuar leyendo&#8230;<\/a><\/p>\n","protected":false},"author":24,"featured_media":4251,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8],"tags":[149,147,18,148,416],"class_list":["post-4237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebra","category-con-estilo","tag-noitedetendas","tag-centro-comercial-aberto-ourense-centro","tag-musica","tag-shopping-night","tag-shopping-night-2017"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/posts\/4237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/comments?post=4237"}],"version-history":[{"count":2,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/posts\/4237\/revisions"}],"predecessor-version":[{"id":8998,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/posts\/4237\/revisions\/8998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/media\/4251"}],"wp:attachment":[{"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/media?parent=4237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/categories?post=4237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maistendencia.com\/blog\/wp-json\/wp\/v2\/tags?post=4237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}